{"id":1027,"date":"2023-10-20T15:03:00","date_gmt":"2023-10-20T13:03:00","guid":{"rendered":"https:\/\/copropriete-binquenais.fr\/?p=1027"},"modified":"2023-10-20T15:05:20","modified_gmt":"2023-10-20T13:05:20","slug":"operation-velos","status":"publish","type":"post","link":"https:\/\/copropriete-binquenais.fr\/index.php\/2023\/10\/20\/operation-velos\/","title":{"rendered":"Op\u00e9ration v\u00e9los"},"content":{"rendered":"\n<p>Le Conseil syndical a constat\u00e9 que les locaux v\u00e9los \u00e9taient encombr\u00e9s de v\u00e9los en mauvais \u00e9tat et\/ou visiblement abandonn\u00e9s.<\/p>\n\n\n\n<p>Apr\u00e8s une campagne d&rsquo;identification des v\u00e9los par les propri\u00e9taires, les v\u00e9los non-identifi\u00e9s seront \u00e9vacu\u00e9s par des ressource ries.<\/p>\n\n\n\n<p>Une fois que les locaux seront d\u00e9barrass\u00e9s des v\u00e9los inutilis\u00e9s, un am\u00e9nagement avec des racks  fix\u00e9s au sol sera r\u00e9alis\u00e9 dans les cages d&rsquo;escalier qui le souhaitent.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Conseil syndical a constat\u00e9 que les locaux v\u00e9los \u00e9taient encombr\u00e9s de v\u00e9los en mauvais \u00e9tat et\/ou visiblement abandonn\u00e9s. Apr\u00e8s une campagne d&rsquo;identification des v\u00e9los par les propri\u00e9taires, les v\u00e9los non-identifi\u00e9s seront \u00e9vacu\u00e9s par des ressource ries. Une fois que les locaux seront d\u00e9barrass\u00e9s des v\u00e9los inutilis\u00e9s, un am\u00e9nagement avec des racks fix\u00e9s au sol &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/copropriete-binquenais.fr\/index.php\/2023\/10\/20\/operation-velos\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Op\u00e9ration v\u00e9los&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1027","post","type-post","status-publish","format-standard","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/copropriete-binquenais.fr\/index.php\/wp-json\/wp\/v2\/posts\/1027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/copropriete-binquenais.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/copropriete-binquenais.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/copropriete-binquenais.fr\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/copropriete-binquenais.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1027"}],"version-history":[{"count":2,"href":"https:\/\/copropriete-binquenais.fr\/index.php\/wp-json\/wp\/v2\/posts\/1027\/revisions"}],"predecessor-version":[{"id":1030,"href":"https:\/\/copropriete-binquenais.fr\/index.php\/wp-json\/wp\/v2\/posts\/1027\/revisions\/1030"}],"wp:attachment":[{"href":"https:\/\/copropriete-binquenais.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/copropriete-binquenais.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/copropriete-binquenais.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}